{"id":1159,"date":"2012-09-21T14:01:22","date_gmt":"2012-09-21T13:01:22","guid":{"rendered":"http:\/\/info-fiction.4o4.ch\/?p=1159"},"modified":"2013-02-25T16:36:42","modified_gmt":"2013-02-25T15:36:42","slug":"sports-body-administration","status":"publish","type":"post","link":"https:\/\/campus.hesge.ch\/informationfiction\/sports-body-administration\/","title":{"rendered":"SPORTS &#8211; BODY- ADMINISTRATION  avec Jules Spinatsch"},"content":{"rendered":"<p>Jules Spinatsch pr&eacute;sente son travail artistique et introduit le workshop<\/p>\n<p><strong>SPORTS &ndash; BODY- ADMINISTRATION &nbsp;<\/strong><\/p>\n<blockquote><p>&laquo;&nbsp;in a non-olympic year we are trying to ask what is it all about anyway&nbsp;&raquo; <em>lately unknown poet<\/em><\/p><\/blockquote>\n<p>La Suisse est le pays dans lequel le sport mondial est organis&eacute;.<br>\nLa majorit&eacute; des f&eacute;d&eacute;rations et organisations internationales sportives sont bas&eacute;es autour de lac Leman:<br>\nLausanne : 23 F&eacute;d&eacute;rations, 19 Organisations.<br>\nZ&uuml;rich : Fifa, IHF<br>\nPour compl&eacute;ter, on trouve &agrave; Zug de nombreuses agences sp&eacute;cialis&eacute;es dans le droit du sport et le marketing.<\/p>\n<p>Le workshop, qui se d&eacute;veloppera sur plusieurs mois, commencera par une investigation sur les structures et les statuts des f&eacute;d&eacute;rations et leurs fonctionnements.<br>\nUne r&eacute;flexion portera sur la fonction du sport dans la soci&eacute;t&eacute; et son poids dans l&rsquo;&eacute;conomie:<br>\n2-3 jours par mois.<br>\nPendant les cours je pr&eacute;senterai des travaux li&eacute;es au sujet, et nous en discuterons.<\/p>\n<p><strong>Champs de la recherche :<\/strong><br>\n(Faits)<br>\n&ndash; Histoire, structures et fonctionnement des f&eacute;d&eacute;rations sportives (d&eacute;but de l&rsquo;histoire en 1893 avec la fondation du IOC &agrave; Lausanne.)<\/p>\n<p>(Id&eacute;al et Propagande)<br>\n&ndash; Id&eacute;es, d&eacute;clarations et images d&rsquo;eux-m&ecirc;mes, identit&eacute;s.<br>\n&ndash; M&eacute;dia-r&eacute;alit&eacute; (m&eacute;dia et perceptions publiques, dernier scandale en date, bilan)<\/p>\n<p>(Politique)<br>\nDilemme et contradicition:&nbsp; la s&eacute;paration du sport et de la politique.<br>\nC&rsquo;est &agrave; dire, &eacute;viter toutes manifestations politiques pendant les spectacles,&nbsp; mais aussi &eacute;viter l&rsquo;influence que les int&eacute;r&ecirc;ts politiques pourraient avoir sur le sport).<\/p>\n<p><strong>P&eacute;riode: d&eacute;cembre 2012 &ndash; septembre 2013<\/strong><br>\n3 &eacute;tapes<br>\nA. INVESTIGATION et ANALYSE &ndash;<br>\nVisites sur places : IOC-Archives. FIFA.<\/p>\n<p>B. CONCEPT et TRAVAUX&nbsp;&ndash; en groupe et sur rendez-vous individuels.<br>\nChaqu&rsquo;un-e propose une id&eacute;e g&eacute;n&eacute;rale pour l&rsquo;ensemble et un projet personnel d&eacute;velopp&eacute; en photographie, en vid&eacute;o, avec des documents d&rsquo;archives, ou encore par la performance.<\/p>\n<p>C. FINALISATION : sous forme d&rsquo;une exposition dans une institution<br>\nou\/et&nbsp; d&rsquo;une publication en septembre-octobre 2013 (date &agrave; pr&eacute;ciser)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jules Spinatsch pr\u00e9sente son travail artistique et introduit le workshop SPORTS &#8211; BODY- ADMINISTRATION \u00a0 \u00ab\u00a0in a non-olympic year we are trying to ask what is it all about anyway\u00a0\u00bb lately unknown poet La Suisse est le pays dans lequel le sport mondial est organis\u00e9. La majorit\u00e9 des f\u00e9d\u00e9rations et organisations internationales sportives sont bas\u00e9es [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[54,10,19,18],"tags":[57],"class_list":["post-1159","post","type-post","status-publish","format-standard","hentry","category-axe-de-travail","category-evenement","category-info","category-workshop","tag-sports-body-administration"],"_links":{"self":[{"href":"https:\/\/campus.hesge.ch\/informationfiction\/wp-json\/wp\/v2\/posts\/1159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/campus.hesge.ch\/informationfiction\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/campus.hesge.ch\/informationfiction\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/campus.hesge.ch\/informationfiction\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/campus.hesge.ch\/informationfiction\/wp-json\/wp\/v2\/comments?post=1159"}],"version-history":[{"count":12,"href":"https:\/\/campus.hesge.ch\/informationfiction\/wp-json\/wp\/v2\/posts\/1159\/revisions"}],"predecessor-version":[{"id":1165,"href":"https:\/\/campus.hesge.ch\/informationfiction\/wp-json\/wp\/v2\/posts\/1159\/revisions\/1165"}],"wp:attachment":[{"href":"https:\/\/campus.hesge.ch\/informationfiction\/wp-json\/wp\/v2\/media?parent=1159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/campus.hesge.ch\/informationfiction\/wp-json\/wp\/v2\/categories?post=1159"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/campus.hesge.ch\/informationfiction\/wp-json\/wp\/v2\/tags?post=1159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}