{"id":398,"date":"2012-08-24T17:04:46","date_gmt":"2012-08-24T16:04:46","guid":{"rendered":"http:\/\/info-fiction.4o4.ch\/?p=398"},"modified":"2013-03-04T22:13:54","modified_gmt":"2013-03-04T21:13:54","slug":"conference-de-jordi-vidal-traite-du-combat-moderne","status":"publish","type":"post","link":"https:\/\/campus.hesge.ch\/informationfiction\/conference-de-jordi-vidal-traite-du-combat-moderne\/","title":{"rendered":"Jordi Vidal: Trait\u00e9 du combat moderne"},"content":{"rendered":"<p><strong>salle de conference &ndash; GD<\/strong><\/p>\n<p>&laquo; Comme le <em>Trait&eacute; du combat moderne<\/em> d&eacute;borde largement le cadre de l&rsquo;essai cinematographique traditionnel, j&rsquo;indiquerai comment l&rsquo;&oelig;uvre de Kubrick, ce perfectionniste maniaque et m&eacute;lancolique, exc&egrave;de le cinema et &eacute;claire d&rsquo;un jour cr&eacute;pusculaire toute l&rsquo;histoire du 20e si&egrave;cle.<\/p>\n<blockquote><p>Reliant pas &agrave; pas la filmographie de Kubrick, je l&rsquo;int&egrave;grerai &agrave; une analyse critique plus vaste de la modernit&eacute; :\n<\/p><\/blockquote>\n<p>Mensonge et guerre sociale avec <em>Barry Lyndon<\/em>, &eacute;loge de la resistance et meditation sur la barbarie avec <em>Les Sentiers de la gloire<\/em>, pouvoir de la d&eacute;linquance et d&eacute;linquance du pouvoir avec <em>Orange m&eacute;canique<\/em>, pens&eacute;e magique avec <em>Shining<\/em>, formes de la d&eacute;r&eacute;alisation avec <em>Lolita<\/em>, guerre de la repr&eacute;sentation avec <em>Full Metal Jacket<\/em>, commentaires sur la soci&eacute;t&eacute; du chaos avec <em>Eyes Wide Shut<\/em>, etc.<\/p>\n<p>Positionnant d&eacute;finitivement Kubrick contre son &eacute;poque et ses strat&eacute;gies de manipulation, je montrerai comment le cin&eacute;aste use lui-m&ecirc;me d&rsquo;une certaine forme de manipulation pour s&eacute;duire le spectateur afin de l&rsquo;attirer par des films &agrave; l&rsquo;apparence romanesque vers une &oelig;uvre exp&eacute;rimentale d&rsquo;une rare complexite (notamment avec <em>Eyes Wide Shut<\/em>).<\/p>\n<p>En manipulant &agrave; mon tour l&rsquo;oeuvre kubrickienne il s&rsquo;agit aussi pour moi de livrer une sorte d&rsquo;autoportrait en creux. Je m&rsquo;appuierai sur les philosophes et les &eacute;crivains des si&egrave;cles passes (<a href=\"https:\/\/campus.hesge.ch\/informationfiction\/encyclopedia\/bruno\/\" target=\"_self\" title=\"\" class=\"encyclopedia\">Bruno<\/a>, Vico, Sterne), pour appr&eacute;hender les probl&egrave;mes les plus contemporains : pouvoir de la t&eacute;l&eacute;vision, simulacre et r&eacute;alite, etc. A la lumiere de l&rsquo;&oelig;uvre de Kubrick, je tenterai, de mani&egrave;re rigoureuse, digressive et pol&eacute;mique d&rsquo;&eacute;clairer le monde dans lequel nous vivons et inviterai &egrave; decouvrir dans ses films des instruments de lutte.<\/p>\n<p>J&rsquo;ai publi&eacute; aux editions Allia en 2002 un essai de critique sociale, <em>R&eacute;sistance au chaos<\/em>. &raquo;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>salle de conference &#8211; GD \u00ab Comme le Trait\u00e9 du combat moderne d\u00e9borde largement le cadre de l&rsquo;essai cinematographique traditionnel, j&rsquo;indiquerai comment l&rsquo;\u0153uvre de Kubrick, ce perfectionniste maniaque et m\u00e9lancolique, exc\u00e8de le cinema et \u00e9claire d&rsquo;un jour cr\u00e9pusculaire toute l&rsquo;histoire du 20e si\u00e8cle. Reliant pas \u00e0 pas la filmographie de Kubrick, je l&rsquo;int\u00e8grerai \u00e0 une [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[13,10],"tags":[],"class_list":["post-398","post","type-post","status-publish","format-standard","hentry","category-conference","category-evenement"],"_links":{"self":[{"href":"https:\/\/campus.hesge.ch\/informationfiction\/wp-json\/wp\/v2\/posts\/398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/campus.hesge.ch\/informationfiction\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/campus.hesge.ch\/informationfiction\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/campus.hesge.ch\/informationfiction\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/campus.hesge.ch\/informationfiction\/wp-json\/wp\/v2\/comments?post=398"}],"version-history":[{"count":12,"href":"https:\/\/campus.hesge.ch\/informationfiction\/wp-json\/wp\/v2\/posts\/398\/revisions"}],"predecessor-version":[{"id":2242,"href":"https:\/\/campus.hesge.ch\/informationfiction\/wp-json\/wp\/v2\/posts\/398\/revisions\/2242"}],"wp:attachment":[{"href":"https:\/\/campus.hesge.ch\/informationfiction\/wp-json\/wp\/v2\/media?parent=398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/campus.hesge.ch\/informationfiction\/wp-json\/wp\/v2\/categories?post=398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/campus.hesge.ch\/informationfiction\/wp-json\/wp\/v2\/tags?post=398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}